{"id":2947,"date":"2018-05-17T14:57:46","date_gmt":"2018-05-17T13:57:46","guid":{"rendered":"https:\/\/www.rajapack.it\/blog-it\/?p=2947"},"modified":"2025-11-03T16:26:32","modified_gmt":"2025-11-03T15:26:32","slug":"partner-eco-responsabile-gli-imballaggi","status":"publish","type":"post","link":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi","title":{"rendered":"Rajapack \u00e8 il tuo partner eco-responsabile per gli imballaggi"},"content":{"rendered":"<h2 data-start=\"286\" data-end=\"321\">Il nostro impegno per l\u2019ambiente<\/h2>\n<p data-start=\"323\" data-end=\"616\">Uno degli impegni pi\u00f9 importanti del <strong data-start=\"360\" data-end=\"375\">Gruppo RAJA<\/strong>, sin dalla sua fondazione, \u00e8 la <strong data-start=\"408\" data-end=\"438\">salvaguardia dell\u2019ambiente<\/strong>.<br data-start=\"439\" data-end=\"442\" \/>Da sempre promuoviamo un modello di crescita sostenibile, basato sull\u2019uso consapevole delle risorse e sulla ricerca costante di <strong data-start=\"570\" data-end=\"613\">soluzioni di imballaggio pi\u00f9 ecologiche<\/strong>.<\/p>\n<p data-start=\"618\" data-end=\"899\">Il nostro percorso verso la sostenibilit\u00e0 \u00e8 iniziato con la vendita di <strong data-start=\"689\" data-end=\"722\">prodotti in cartone riciclato<\/strong>, ma oggi coinvolge ogni aspetto della nostra attivit\u00e0: dalla scelta dei materiali all\u2019ottimizzazione della logistica, fino alla riduzione delle emissioni legate al trasporto.<\/p>\n<p data-start=\"901\" data-end=\"1115\">Crediamo che ogni scelta possa fare la differenza. Per questo, <strong data-start=\"964\" data-end=\"994\">per ogni linea di prodotto<\/strong>, ti offriamo sempre <strong data-start=\"1015\" data-end=\"1043\">un\u2019alternativa ecologica<\/strong> che unisce prestazioni elevate, resistenza e rispetto per l\u2019ambiente.<\/p>\n<p data-start=\"901\" data-end=\"1115\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6173 size-full\" src=\"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/IMBALLAGGI-ECOLOGICI-INFOGRAFICA-03-scaled.jpg\" alt=\"\" width=\"1650\" height=\"2560\" srcset=\"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/IMBALLAGGI-ECOLOGICI-INFOGRAFICA-03-scaled.jpg 1650w, https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/IMBALLAGGI-ECOLOGICI-INFOGRAFICA-03-277x430.jpg 277w, https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/IMBALLAGGI-ECOLOGICI-INFOGRAFICA-03-660x1024.jpg 660w, https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/IMBALLAGGI-ECOLOGICI-INFOGRAFICA-03-768x1192.jpg 768w, https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/IMBALLAGGI-ECOLOGICI-INFOGRAFICA-03-990x1536.jpg 990w, https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/IMBALLAGGI-ECOLOGICI-INFOGRAFICA-03-1320x2048.jpg 1320w\" sizes=\"(max-width: 1650px) 100vw, 1650px\" \/><\/p>\n<h2 data-start=\"1122\" data-end=\"1158\">La nostra linea di prodotti green<\/h2>\n<p data-start=\"1160\" data-end=\"1369\">I nostri <strong data-start=\"1169\" data-end=\"1193\">prodotti sostenibili<\/strong> sono pensati per garantire la massima protezione dei tuoi imballaggi, riducendo l\u2019impatto ambientale grazie all\u2019uso di <strong data-start=\"1313\" data-end=\"1366\">materiali riciclati, riciclabili o biodegradabili<\/strong>.<\/p>\n<p data-start=\"1371\" data-end=\"1473\">Ecco alcune delle nostre soluzioni pi\u00f9 ecologiche, illustrate anche nella nostra infografica dedicata:<\/p>\n<p>Le nostre\u00a0<a href=\"https:\/\/www.rajapack.it\/borse-confezioni-regalo\/sacchetti-plastica\/sacchetti-biodegradabili\/buste-shopper-biodegradabile-amido-di-patata_OFF_IT_0227.html\">shopper biodegradabili<\/a>\u00a0sono prodotte con amido di patata<\/p>\n<p>Il <a href=\"https:\/\/www.rajapack.it\/nastri-adesivi-regge\/nastri-adesivi-regge-ecologiche\/nastri-adesivi-ecologici\/nastro-adesivo-85-percento-pet-riciclato_OFF_IT_008703.html\">Nastro adesivo 85% PET riciclato<\/a> \u00e8<\/p>\n<p>Il\u00a0<a class=\"ext-link\" title=\"\" href=\"https:\/\/www.rajapack.it\/imballaggi-protettivi-riempimento\/film-bolle-aria\/film-bolle-aria-rotolo\/film-bolle-aria-riciclato-rajabul_PDT248586.html?utm_source=BLOG\" rel=\"external nofollow\">film a bolle rigenerato<\/a>\u00a0\u00e8 fabbricato con plastica 100% rigenerata!<\/p>\n<p>Il\u00a0<a class=\"ext-link\" title=\"\" href=\"https:\/\/www.rajapack.it\/film-estensibile-pallettizzazione\/pallet\/pallet-legno-pressato\/mini-pallet-legno-pressato-inka_OFF_IT_0092.html?utm_source=BLOG\" rel=\"external nofollow\">pallet in legno pressato INKA<\/a>, non \u00e8 solo sicuro grazie all&#8217;assenza di chiodi o angoli vivi ma \u00e8 anche riciclabile e biodegrabile.<\/p>\n<h2 data-start=\"2383\" data-end=\"2425\">Una logistica sostenibile per il futuro<\/h2>\n<p data-start=\"2427\" data-end=\"2686\">Ogni giorno ci impegniamo per <strong data-start=\"2457\" data-end=\"2541\">ridurre i rifiuti, ottimizzare i trasporti e promuovere materiali riutilizzabili<\/strong>. Il nostro obiettivo \u00e8 rendere la <strong data-start=\"2576\" data-end=\"2615\">catena di fornitura pi\u00f9 sostenibile<\/strong> e supportare le aziende che, come noi, scelgono un futuro pi\u00f9 verde.<\/p>\n<p data-start=\"2688\" data-end=\"2853\">Con la gamma di imballaggi sostenibili <strong data-start=\"2701\" data-end=\"2726\">Rajapack<\/strong>, puoi imballare, proteggere e spedire in modo efficiente, senza rinunciare alla qualit\u00e0 n\u00e9 alla sicurezza dei tuoi prodotti.<\/p>\n<p data-start=\"2855\" data-end=\"2965\">&#x1f449; <strong data-start=\"2858\" data-end=\"2965\">Scopri tutta la nostra <a href=\"https:\/\/www.rajapack.it\/imballaggi-ecologici_cms_000041.html\">selezione di imballaggi ecologici<\/a> su rajapack.it e scegli di fare la differenza!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nostro impegno per l\u2019ambiente Uno degli impegni pi\u00f9 importanti del Gruppo RAJA, sin dalla sua fondazione, \u00e8 la salvaguardia dell\u2019ambiente.Da sempre promuoviamo un modello di crescita sostenibile, basato sull\u2019uso [&#8230;]<\/p>\n","protected":false},"author":24,"featured_media":6168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[451],"tags":[496],"class_list":["post-2947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecologia","tag-sostenibilita"],"acf":[],"yoast_head":"\n<title>Imballaggi ecologici che fanno la differenza - Blog Rajapack<\/title>\n<meta name=\"description\" content=\"Imballaggi ecologici per aziende italiane: soluzioni in cartone riciclato, PET rigenerato e materiali biodegradabili per spedizioni pi\u00f9 sostenibili.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imballaggi ecologici che fanno la differenza - Blog Rajapack\" \/>\n<meta property=\"og:description\" content=\"Imballaggi ecologici per aziende italiane: soluzioni in cartone riciclato, PET rigenerato e materiali biodegradabili per spedizioni pi\u00f9 sostenibili.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ufficiale RAJA | Il n\u00b0 1 Europeo dell\u2019imballaggio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RajapackIT\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-17T13:57:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T15:26:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Maria Tognon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RajapackIT\" \/>\n<meta name=\"twitter:site\" content=\"@RajapackIT\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Tognon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\/\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Maria Tognon\",\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/person\/8293b8c9692591d18b2bbc2943fdade9\"\n\t            },\n\t            \"headline\": \"Rajapack \u00e8 il tuo partner eco-responsabile per gli imballaggi\",\n\t            \"datePublished\": \"2018-05-17T13:57:46+00:00\",\n\t            \"dateModified\": \"2025-11-03T15:26:32+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi\"\n\t            },\n\t            \"wordCount\": 303,\n\t            \"commentCount\": 0,\n\t            \"publisher\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#organization\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp\",\n\t            \"keywords\": [\n\t                \"Sostenibilit\u00e0\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Sostenibilit\u00e0 e imballaggi\"\n\t            ],\n\t            \"inLanguage\": \"it-IT\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"CommentAction\",\n\t                    \"name\": \"Comment\",\n\t                    \"target\": [\n\t                        \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#respond\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi\",\n\t            \"url\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi\",\n\t            \"name\": \"Imballaggi ecologici che fanno la differenza - Blog Rajapack\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp\",\n\t            \"datePublished\": \"2018-05-17T13:57:46+00:00\",\n\t            \"dateModified\": \"2025-11-03T15:26:32+00:00\",\n\t            \"description\": \"Imballaggi ecologici per aziende italiane: soluzioni in cartone riciclato, PET rigenerato e materiali biodegradabili per spedizioni pi\u00f9 sostenibili.\",\n\t            \"inLanguage\": \"it-IT\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"it-IT\",\n\t            \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage\",\n\t            \"url\": \"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp\",\n\t            \"contentUrl\": \"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp\",\n\t            \"width\": 1024,\n\t            \"height\": 520,\n\t            \"caption\": \"imballaggi sostenibili\"\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#website\",\n\t            \"url\": \"https:\/\/www.rajapack.it\/blog-it\/\",\n\t            \"name\": \"Blog Ufficiale RAJA | Il n\u00b0 1 Europeo dell\u2019imballaggio\",\n\t            \"description\": \"news dal mondo dell&#039;imballaggio\",\n\t            \"publisher\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#organization\"\n\t            },\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\/\/www.rajapack.it\/blog-it\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": \"required name=search_term_string\"\n\t                }\n\t            ],\n\t            \"inLanguage\": \"it-IT\"\n\t        },\n\t        {\n\t            \"@type\": \"Organization\",\n\t            \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#organization\",\n\t            \"name\": \"RAJA Blog IT\",\n\t            \"url\": \"https:\/\/www.rajapack.it\/blog-it\/\",\n\t            \"logo\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"it-IT\",\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/logo\/image\/\",\n\t                \"url\": \"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2022\/07\/ico.png\",\n\t                \"contentUrl\": \"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2022\/07\/ico.png\",\n\t                \"width\": 512,\n\t                \"height\": 512,\n\t                \"caption\": \"RAJA Blog IT\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/logo\/image\/\"\n\t            },\n\t            \"sameAs\": [\n\t                \"https:\/\/www.facebook.com\/RajapackIT\",\n\t                \"https:\/\/x.com\/RajapackIT\",\n\t                \"http:\/\/www.linkedin.com\/company\/rajapack-italy\"\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/person\/8293b8c9692591d18b2bbc2943fdade9\",\n\t            \"name\": \"Maria Tognon\",\n\t            \"image\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"it-IT\",\n\t                \"@id\": \"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/person\/image\/\",\n\t                \"url\": \"https:\/\/secure.gravatar.com\/avatar\/68ed3f0a2f693fe28b5de06e0fc5ea50?s=96&d=mm&r=g\",\n\t                \"contentUrl\": \"https:\/\/secure.gravatar.com\/avatar\/68ed3f0a2f693fe28b5de06e0fc5ea50?s=96&d=mm&r=g\",\n\t                \"caption\": \"Maria Tognon\"\n\t            },\n\t            \"description\": \"Lorem Ipsum \u00e8 un testo segnaposto utilizzato nel settore della tipografia e della stampa.\"\n\t        }\n\t    ]\n\t}<\/script>\n","yoast_head_json":{"title":"Imballaggi ecologici che fanno la differenza - Blog Rajapack","description":"Imballaggi ecologici per aziende italiane: soluzioni in cartone riciclato, PET rigenerato e materiali biodegradabili per spedizioni pi\u00f9 sostenibili.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi","og_locale":"it_IT","og_type":"article","og_title":"Imballaggi ecologici che fanno la differenza - Blog Rajapack","og_description":"Imballaggi ecologici per aziende italiane: soluzioni in cartone riciclato, PET rigenerato e materiali biodegradabili per spedizioni pi\u00f9 sostenibili.","og_url":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi","og_site_name":"Blog Ufficiale RAJA | Il n\u00b0 1 Europeo dell\u2019imballaggio","article_publisher":"https:\/\/www.facebook.com\/RajapackIT","article_published_time":"2018-05-17T13:57:46+00:00","article_modified_time":"2025-11-03T15:26:32+00:00","og_image":[{"width":1024,"height":520,"url":"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp","type":"image\/webp"}],"author":"Maria Tognon","twitter_card":"summary_large_image","twitter_creator":"@RajapackIT","twitter_site":"@RajapackIT","twitter_misc":{"Scritto da":"Maria Tognon","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#article","isPartOf":{"@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi"},"author":{"name":"Maria Tognon","@id":"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/person\/8293b8c9692591d18b2bbc2943fdade9"},"headline":"Rajapack \u00e8 il tuo partner eco-responsabile per gli imballaggi","datePublished":"2018-05-17T13:57:46+00:00","dateModified":"2025-11-03T15:26:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi"},"wordCount":303,"commentCount":0,"publisher":{"@id":"https:\/\/www.rajapack.it\/blog-it\/#organization"},"image":{"@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage"},"thumbnailUrl":"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp","keywords":["Sostenibilit\u00e0"],"articleSection":["Sostenibilit\u00e0 e imballaggi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi","url":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi","name":"Imballaggi ecologici che fanno la differenza - Blog Rajapack","isPartOf":{"@id":"https:\/\/www.rajapack.it\/blog-it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage"},"image":{"@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage"},"thumbnailUrl":"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp","datePublished":"2018-05-17T13:57:46+00:00","dateModified":"2025-11-03T15:26:32+00:00","description":"Imballaggi ecologici per aziende italiane: soluzioni in cartone riciclato, PET rigenerato e materiali biodegradabili per spedizioni pi\u00f9 sostenibili.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rajapack.it\/blog-it\/partner-eco-responsabile-gli-imballaggi#primaryimage","url":"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp","contentUrl":"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2018\/05\/imballaggi-sostenibili.webp","width":1024,"height":520,"caption":"imballaggi sostenibili"},{"@type":"WebSite","@id":"https:\/\/www.rajapack.it\/blog-it\/#website","url":"https:\/\/www.rajapack.it\/blog-it\/","name":"Blog Ufficiale RAJA | Il n\u00b0 1 Europeo dell\u2019imballaggio","description":"news dal mondo dell&#039;imballaggio","publisher":{"@id":"https:\/\/www.rajapack.it\/blog-it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rajapack.it\/blog-it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rajapack.it\/blog-it\/#organization","name":"RAJA Blog IT","url":"https:\/\/www.rajapack.it\/blog-it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/logo\/image\/","url":"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2022\/07\/ico.png","contentUrl":"https:\/\/www.rajapack.it\/blog-it\/wp-content\/uploads\/2022\/07\/ico.png","width":512,"height":512,"caption":"RAJA Blog IT"},"image":{"@id":"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RajapackIT","https:\/\/x.com\/RajapackIT","http:\/\/www.linkedin.com\/company\/rajapack-italy"]},{"@type":"Person","@id":"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/person\/8293b8c9692591d18b2bbc2943fdade9","name":"Maria Tognon","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rajapack.it\/blog-it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/68ed3f0a2f693fe28b5de06e0fc5ea50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ed3f0a2f693fe28b5de06e0fc5ea50?s=96&d=mm&r=g","caption":"Maria Tognon"},"description":"Lorem Ipsum \u00e8 un testo segnaposto utilizzato nel settore della tipografia e della stampa."}]}},"_links":{"self":[{"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/posts\/2947"}],"collection":[{"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/comments?post=2947"}],"version-history":[{"count":3,"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/posts\/2947\/revisions"}],"predecessor-version":[{"id":6171,"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/posts\/2947\/revisions\/6171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/media\/6168"}],"wp:attachment":[{"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/media?parent=2947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/categories?post=2947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rajapack.it\/blog-it\/wp-json\/wp\/v2\/tags?post=2947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}